{"id":5090,"date":"2022-05-10T17:15:39","date_gmt":"2022-05-10T15:15:39","guid":{"rendered":"https:\/\/blogs.etsii.urjc.es\/dseytr\/?p=5090"},"modified":"2022-06-03T10:04:14","modified_gmt":"2022-06-03T08:04:14","slug":"autolavado","status":"publish","type":"post","link":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/","title":{"rendered":"Autolavado"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Autores: Iv\u00e1n Fallos Mora, Javier S\u00e1nchez Almansa, Manuel Torralba Cepeda (GRUPO 3 &#8211; Ingenier\u00eda Inform\u00e1tica (M\u00f3stoles)<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/52062104364_12e61ec3b7_k.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">MATERIALES UTILIZADOS:<\/h2>\n\n\n\n<p class=\"has-text-align-left\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Del <strong>malet\u00edn<\/strong> proporcionado por la universidad, pudimos aprovechar la placa Arduino, el servomotor, y algunos cables y LEDs.<\/p>\n\n\n\n<p class=\"has-text-align-left\"> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <strong>Reutilizamos<\/strong> algunos materiales: De una impresora obtuvimos una varilla met\u00e1lica con reductora y varios motores de 5V. De un aparato que dej\u00f3 de funcionar extrajimos el ventilador, y, de un juguete, el dep\u00f3sito de pilas. Adem\u00e1s, reutilizamos otros materiales que ten\u00edamos por casa: un cilindro de cart\u00f3n, varias tablas y una l\u00e1mina de papel lija.<\/p>\n\n\n\n<p class=\"has-text-align-left\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Adem\u00e1s, tuvimos que <strong>adquirir<\/strong> 2 rel\u00e9s de 5v (2,40\u20ac), una l\u00e1mina de goma eva negra (0,50\u20ac), unos mini rodillos de pintura (0,90\u20ac), algunas escuadras met\u00e1licas (0,75\u20ac) y unas arandelas (0,60\u20ac).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CONSTRUCCI\u00d3N<\/h2>\n\n\n\n<p> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Esta fase consist\u00eda en el trabajo f\u00edsico: cortar madera, hacer agujeros con brocas (y sin taladro)\u2026 Entre otras labores que requer\u00edan destreza, ma\u00f1a y fuerza. As\u00ed pues, disponiendo de todos los materiales, las herramientas y las maderas reci\u00e9n cortadas y taladradas, comenzamos el montaje. Nuestro autolavado se compone de una gran plancha de madera, que sostiene toda la estructura as\u00ed como todo el circuito: motores, placas, cables, etc. Esta estructura est\u00e1 formada por una plancha de madera, delimitada por otras dos planchas de menor anchura y con agujeros en a sus extremos. Por dichos agujeros pasan las barras de metal con los tubos (que anteriormente revestimos con papel de lija para que agarrase la cinta), los cuales har\u00e1n girar la cinta transportadora, formada por goma eva. Todas las uniones de materiales las hemos hecho con silicona caliente (con una pistola termofusible) y cola.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FUNCIONAMIENTO<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; -Fases de <strong>enjabonado y aclarado<\/strong>: se representan con un led azul, simulando agua, y un led blanco simulando jab\u00f3n. Ambos pegados en el lateral interior de las dos planchas con agujeros.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; -Fase de <strong>limpiado<\/strong>: consta de dos rodillos limpiadores, para los que hemos usado dos rodillos de pintura. Est\u00e1n unidos a un motor cada uno.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; -Fase de <strong>secado<\/strong>: encima de la cinta se encuentra un ventilador, colocado mediante dos tablillas de madera. A su salo aparece un led rojo simulando el calor del secado.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; -Fase de <strong>salida<\/strong>: se representa con un led de color verde, para hacer ver al usuario que el proceso ha finalizado y puede recoger su coche.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PROGRAMACI\u00d3N<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; El c\u00f3digo del proyecto se realiz\u00f3 en paralelo a la construcci\u00f3n del modelo a escala. En un principio pensamos en usar sensores que, por cada fase del ciclo de lavado, detectaran la posici\u00f3n del veh\u00edculo para parar el movimiento de la cinta en el momento justo. Desechamos la idea debido a m\u00faltiples problemas t\u00e9cnicos. Entre ellos escasez de pines en la placa y falta de espacio en el prototipo para colocar los sensores.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Decidimos implementar el funcionamiento con tiempos. Para ello primero se escribi\u00f3 todo el c\u00f3digo que activaba las diferentes fases (agua, rodillos, secado) en el orden adecuado. Una vez terminada la maqueta y verificado que todo se encendiese correctamente (al principio los motores no funcionaban, y tuvimos que comprar rel\u00e9s), usamos un coche de juguete para medir los distintos tiempos que ten\u00eda que estar la cinta en movimiento y los tiempos de cada fase para que el resultado fuera realista.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La barrera s\u00ed hace uso de un sensor de distancias que detecta los nuevos clientes. Si ya hay un coche haciendo uso del autolavado esta no se abre hasta que el proceso de lavado acaba. Por el contrario, si no hay nadie haciendo uso del servicio,&nbsp; la barrera se levanta para dejar acceso al nuevo cliente. Una vez el coche deja de ser detectado por el sensor se espera 4 segundos para asegurarse que haya pasado completamente y evitar da\u00f1ar as\u00ed el veh\u00edculo o la barrera.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\n#include\n\nconst float sonido = 34300.0; \/\/ Velocidad del sonido en cm\/s\n\n\/\/ Variables para el control de la barrera\n\/\/   Sensor de distancia\nconst int pinTrigger = 3;\nconst int pinEcho = 4;\nfloat distancia;\nfloat umbralActivacion = 10; \/\/ Distancia en cm a la que la barrera se activa\n\/\/   Servo de la barrera\nServo barrera;\nconst int pinBarrera = 2;\nconst int gradosAbierto = 90;\nconst int gradosCerrado = 0;\n\nconst int pinCinta = 12;\nconst int pinAguaInicio = 5;\nconst int pinRodillos = 10;\nconst int pinAguaFin = 6;\nconst int pinVentilador = 7;\nconst int pinLedVerde = 8;\n\nvoid setup()\n{ \n  pinMode(pinCinta, OUTPUT);\n  pinMode(pinRodillos, OUTPUT);\n  pinMode(pinTrigger, OUTPUT);\n  pinMode(pinEcho, INPUT);\n  pinMode(pinAguaInicio, OUTPUT);\n  pinMode(pinAguaFin, OUTPUT);\n  pinMode(pinVentilador, OUTPUT);\n  pinMode(pinLedVerde, OUTPUT);\n  \n  barrera.attach(pinBarrera);\n  \n  Serial.begin(9600);\n\n  barrera.write(gradosCerrado);\n}\n\nvoid loop()\n{ \n  iniciarTrigger(pinTrigger);\n  distancia = calcularDistancia(pinEcho);\n  \n  Serial.println(distancia);\n  \n  if (distancia &lt; umbralActivacion) { \/\/ Si la distancia es menor de 20 centimetros\n    \/\/ Abre la barrera, detecta cuando el coche pasa y la cierra\n    barrera.write(gradosAbierto);\n    while (distancia &lt; umbralActivacion) {\n      iniciarTrigger(pinTrigger);\n      distancia = calcularDistancia(pinEcho);\n    }\n    delay(4000);\n    barrera.write(gradosCerrado);\n    cicloLavado();\n  }\n}\n\nvoid desplazarCinta(int tiempo) {\n  digitalWrite(pinCinta, HIGH);\n  delay(tiempo);\n  digitalWrite(pinCinta, LOW);\n}\n\nvoid cicloLavado() {\n  delay(2000);\n  \n  \/\/ AGUA INICIO\n  Serial.println(\"Agua de inicio\");\n  digitalWrite(pinAguaInicio, HIGH);\n  delay(2000);\n  desplazarCinta(200);\n  delay(2000);\n  digitalWrite(pinAguaInicio, LOW);\n\n  delay(500);\n  desplazarCinta(200);\n  \n  \n  \/\/ RODILLOS\n  Serial.println(\"Rodillos\");\n  delay(500);\n  digitalWrite(pinRodillos, HIGH);\n  delay(1000);\n  desplazarCinta(100); \/\/ Durante rodillos\n  delay(1000);\n  desplazarCinta(100); \/\/ Durante rodillos\n  delay(1000);\n  desplazarCinta(100);\n  delay(200);\n  digitalWrite(pinRodillos, LOW);\n  desplazarCinta(100);\n  \n  \/\/ AGUA ENJUAGADO\n  delay(500);\n  Serial.println(\"Agua de enjuage\");\n  digitalWrite(pinAguaFin, HIGH);\n  delay(2000);\n  desplazarCinta(100);\n  delay(2000);\n  desplazarCinta(100);\n  delay(2000);\n  digitalWrite(pinAguaFin, LOW);\n  delay(500);\n\n  desplazarCinta(300);\n  \n  \/\/ SECADO\n  Serial.println(\"Secado\");\n  digitalWrite(pinVentilador, HIGH);\n  delay(3000);\n  desplazarCinta(150);\n  delay(3000);\n  digitalWrite(pinVentilador, LOW);\n  Serial.println(\"Fin de secado\");\n  \n  delay(1000);\n  \n  digitalWrite(pinLedVerde, HIGH);\n  desplazarCinta(600); \/\/ Sacar coche\n  delay(5000);\n  Serial.println(\"FIN\");\n  digitalWrite(pinLedVerde, LOW);\n}\n\n\/\/ Funciones para detector de distancia\n\nvoid iniciarTrigger(int pinTrigger)\n{\n  \/\/ Ponemos el Triiger en estado bajo y esperamos 2 ms\n  digitalWrite(pinTrigger, LOW);\n  delayMicroseconds(2);\n \n  \/\/ Ponemos el pin Trigger a estado alto y esperamos 10 ms\n  digitalWrite(pinTrigger, HIGH);\n  delayMicroseconds(10);\n \n  \/\/ Comenzamos poniendo el pin Trigger en estado bajo\n  digitalWrite(pinTrigger, LOW);\n}\n\nfloat calcularDistancia(int pinEcho)\n{\n  \/\/ La funci\u00f3n pulseIn obtiene el tiempo que tarda en cambiar entre estados, en este caso a HIGH\n  unsigned long tiempo = pulseIn(pinEcho, HIGH);\n<\/code>\n<\/pre>\n\n\n\n<h2 class=\"wp-block-heading\">DIFICULTADES Y PUNTOS PARA RESE\u00d1AR<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A lo largo de todo el desarrollo del proyecto nos hemos encontrado varias dificultades y aspectos a se\u00f1alar. Algunos de dichos puntos son:<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; En un principio valoramos la posibilidad de introducir agua real en el proyecto. Sin embargo, descartamos est\u00e1 opci\u00f3n puesto que resultar\u00eda dif\u00edcil proteger con seguridad todos los contactos y cables.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; Algunos cables del malet\u00edn ven\u00edan defectuosos. Tardamos tiempo en darnos cuenta de ello, puesto que pens\u00e1bamos que los errores vendr\u00edan de otra parte (componentes, la protoboard\u2026).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; Necesitamos introducir rel\u00e9s, ya que el voltaje proporcionado por la placa no resultaba suficiente para mover los componentes. Al introducirlos, se solucion\u00f3 el problema para el ventilador y la cinta, aunque para los rodillos fue necesario aportar alimentaci\u00f3n externa (con un dep\u00f3sito de pilas).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CASO DE USO<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Autolavado\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/JROkLvhkyAg?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">CONCLUSI\u00d3N<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Como visi\u00f3n global, hay que destacar los conceptos aprendidos; cada uno de nosotros ya hab\u00eda programado en Arduino, pero esta pr\u00e1ctica nos ha servido para afianzar esos conocimientos, a la par que nos ha ayudado a mejoras nuestras capacidades a la hora de dise\u00f1ar y construir estructuras, as\u00ed como el trabajo en equipo, que siempre es importante, dentro y fuera de la Universidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">VIDEO CON EXPLICACIONES<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Grupo3 SSEE Con explicaci\u00f3n\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/eyjimoIj6bE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Autores: Iv\u00e1n Fallos Mora, Javier S\u00e1nchez Almansa, Manuel Torralba Cepeda (GRUPO 3 &#8211; Ingenier\u00eda Inform\u00e1tica (M\u00f3stoles) MATERIALES UTILIZADOS: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Del malet\u00edn proporcionado por la universidad, pudimos aprovechar la placa Arduino, el servomotor, y algunos&#46;&#46;&#46;<\/p>\n","protected":false},"author":39,"featured_media":5091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autolavado - Proyectos con Arduino.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autolavado - Proyectos con Arduino.\" \/>\n<meta property=\"og:description\" content=\"Autores: Iv\u00e1n Fallos Mora, Javier S\u00e1nchez Almansa, Manuel Torralba Cepeda (GRUPO 3 &#8211; Ingenier\u00eda Inform\u00e1tica (M\u00f3stoles) MATERIALES UTILIZADOS: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Del malet\u00edn proporcionado por la universidad, pudimos aprovechar la placa Arduino, el servomotor, y algunos&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectos con Arduino.\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T15:15:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-03T08:04:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/1651569031860-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Autolavado\",\"datePublished\":\"2022-05-10T15:15:39+00:00\",\"dateModified\":\"2022-06-03T08:04:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/\"},\"wordCount\":1052,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/1651569031860-scaled.jpg\",\"articleSection\":[\"Proyectos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/\",\"url\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/\",\"name\":\"Autolavado - Proyectos con Arduino.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/1651569031860-scaled.jpg\",\"datePublished\":\"2022-05-10T15:15:39+00:00\",\"dateModified\":\"2022-06-03T08:04:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/1651569031860-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/1651569031860-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"Autolavado: vista general\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/autolavado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autolavado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#website\",\"url\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/\",\"name\":\"Proyectos con Arduino.\",\"description\":\"Blog de proyectos de Arduino de alumnos de la URJC\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#organization\",\"name\":\"Universidad Rey Juan Carlos\",\"url\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/logourjc-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/05\\\/logourjc-1.jpg\",\"width\":745,\"height\":288,\"caption\":\"Universidad Rey Juan Carlos\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/blogs.etsii.urjc.es\\\/dseytr\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autolavado - Proyectos con Arduino.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/","og_locale":"es_ES","og_type":"article","og_title":"Autolavado - Proyectos con Arduino.","og_description":"Autores: Iv\u00e1n Fallos Mora, Javier S\u00e1nchez Almansa, Manuel Torralba Cepeda (GRUPO 3 &#8211; Ingenier\u00eda Inform\u00e1tica (M\u00f3stoles) MATERIALES UTILIZADOS: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Del malet\u00edn proporcionado por la universidad, pudimos aprovechar la placa Arduino, el servomotor, y algunos&#46;&#46;&#46;","og_url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/","og_site_name":"Proyectos con Arduino.","article_published_time":"2022-05-10T15:15:39+00:00","article_modified_time":"2022-06-03T08:04:14+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/1651569031860-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#article","isPartOf":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/"},"author":{"name":"","@id":""},"headline":"Autolavado","datePublished":"2022-05-10T15:15:39+00:00","dateModified":"2022-06-03T08:04:14+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/"},"wordCount":1052,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#organization"},"image":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/1651569031860-scaled.jpg","articleSection":["Proyectos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/","url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/","name":"Autolavado - Proyectos con Arduino.","isPartOf":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#primaryimage"},"image":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/1651569031860-scaled.jpg","datePublished":"2022-05-10T15:15:39+00:00","dateModified":"2022-06-03T08:04:14+00:00","breadcrumb":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#primaryimage","url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/1651569031860-scaled.jpg","contentUrl":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/1651569031860-scaled.jpg","width":2560,"height":1440,"caption":"Autolavado: vista general"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/autolavado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.etsii.urjc.es\/dseytr\/"},{"@type":"ListItem","position":2,"name":"Autolavado"}]},{"@type":"WebSite","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#website","url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/","name":"Proyectos con Arduino.","description":"Blog de proyectos de Arduino de alumnos de la URJC","publisher":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.etsii.urjc.es\/dseytr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#organization","name":"Universidad Rey Juan Carlos","url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/logourjc-1.jpg","contentUrl":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-content\/uploads\/sites\/8\/2022\/05\/logourjc-1.jpg","width":745,"height":288,"caption":"Universidad Rey Juan Carlos"},"image":{"@id":"https:\/\/blogs.etsii.urjc.es\/dseytr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/blogs.etsii.urjc.es\/dseytr\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/posts\/5090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/comments?post=5090"}],"version-history":[{"count":13,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/posts\/5090\/revisions"}],"predecessor-version":[{"id":5803,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/posts\/5090\/revisions\/5803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/media\/5091"}],"wp:attachment":[{"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/media?parent=5090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/categories?post=5090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.etsii.urjc.es\/dseytr\/wp-json\/wp\/v2\/tags?post=5090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}